{"id":424,"date":"2026-02-07T06:20:16","date_gmt":"2026-02-07T06:20:16","guid":{"rendered":"https:\/\/cartervalves.com\/?page_id=424"},"modified":"2026-02-18T15:38:07","modified_gmt":"2026-02-18T15:38:07","slug":"carter-valve-products","status":"publish","type":"page","link":"https:\/\/cartervalves.com\/nl\/carter-valve-products\/","title":{"rendered":"Carter klepproducten"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"424\" class=\"elementor elementor-424\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24702cd e-flex e-con-boxed e-con e-parent\" data-id=\"24702cd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a47b5d elementor-widget elementor-widget-heading\" data-id=\"7a47b5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">CARTER VALVE PRODUCTS<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd27c28 elementor-widget elementor-widget-heading\" data-id=\"fd27c28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Industrial Valve Products for Critical Service Applications<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac7d0ba elementor-widget elementor-widget-text-editor\" data-id=\"ac7d0ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Carter Valve provides industrial valves and engineered packages for flow control, isolation, and overpressure protection across demanding process and utility systems. Our product portfolio covers control valves, high-performance isolation valves, safety relief solutions, steam\/condensate equipment, and engineered stations\u2014selected to help operators achieve predictable performance, lower leakage risk, and easier maintenance.<\/p><p class=\"p1\">From high-temperature refining services to cryogenic LNG isolation and molecular sieve applications, we support engineers and procurement teams with clear specifications, material options, and selection guidance\u2014so you can move from \u201cvalve type\u201d to a purchase-ready datasheet faster.<\/p><p class=\"p1\">Use the categories below to browse by function, then narrow by size, pressure class, temperature range, end connections, and actuation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f8d654 elementor-widget elementor-widget-button\" data-id=\"8f8d654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Request A Quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dcb35a8 e-flex e-con-boxed e-con e-parent\" data-id=\"dcb35a8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5dc722 e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"c5dc722\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;horizontal_scroll_mobile&quot;:&quot;enable&quot;,&quot;horizontal_scroll&quot;:&quot;disable&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"207472418\" aria-label=\"Tabs. Open items with Enter or Space, close with Escape and navigate using the Arrow keys.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-2074724181\" data-tab-title-id=\"e-n-tab-title-2074724181\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-2074724181\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tControl Valves\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2074724182\" data-tab-title-id=\"e-n-tab-title-2074724182\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2074724182\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tIsolation  Valves\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2074724183\" data-tab-title-id=\"e-n-tab-title-2074724183\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2074724183\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tSafety Valves\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2074724184\" data-tab-title-id=\"e-n-tab-title-2074724184\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2074724184\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tSteam Trapping\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2074724185\" data-tab-title-id=\"e-n-tab-title-2074724185\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2074724185\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tActuator\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2074724186\" data-tab-title-id=\"e-n-tab-title-2074724186\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2074724186\" style=\"--n-tabs-title-order: 6;\">\n\t\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tSystems\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-2074724181\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2074724181\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-ca9157c e-con-full e-flex e-con e-child\" data-id=\"ca9157c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee22ce6 elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"ee22ce6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Grid -->\n\t\t<link id='font-awesome-css' href='https:\/\/cartervalves.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/cartervalves.com\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Post Grid *\/\n\n\r\n@keyframes uc_post_grid_elementor_ee22ce6__item-animation {\r\n  0% {\r\n            \r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            \r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_ee22ce6 .ue-item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_ee22ce6 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_post_grid_elementor_ee22ce6 .uc-entrance-animate {\r\n\tanimation: uc_post_grid_elementor_ee22ce6__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_post_grid_elementor_ee22ce6{\n  min-height: 1px;\n}\n\n#uc_post_grid_elementor_ee22ce6.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n#uc_post_grid_elementor_ee22ce6 .uc_post_grid_style_one_item{\n  position:relative;\n}\n\n#uc_post_grid_elementor_ee22ce6 .uc_post_image{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor_ee22ce6 .uc_post_image img{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\t\n\n#uc_post_grid_elementor_ee22ce6 .uc_post_image_overlay{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_ee22ce6 .uc_more_btn-custom-field{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_ee22ce6 .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_grid_elementor_ee22ce6 .ue-grid-item-posttype{\n  display:inline-block;\n  position: relative;\n  z-index: 1;\n}\n\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor_ee22ce6.uc_post_grid_style_one.ue-list-view .uc_content{\n flex-grow:1;\n}\n\n\n  #uc_post_grid_elementor_ee22ce6:not(.ue-list-view) .ue_post_grid_item{\n    display:flex;\n    flex-direction:column;\n  }\n  \n  #uc_post_grid_elementor_ee22ce6.uc_post_grid_style_one:not(.ue-list-view) .uc_content{\n   flex-grow:1;\n  }\n\n  #uc_post_grid_elementor_ee22ce6.uc_post_grid_style_one .uc_content > div{\n    height:100%;\n    display:flex;\n    flex-direction:column;\n      }\n\n  \n\n\n\n\n\n\n\n\n\n\n\n\n\/*  for grid\/list layout switcher*\/\n\t#uc_post_grid_elementor_ee22ce6.ue-list-view .uc_post_grid_style_one_item {\n     display:flex;  \n     flex-direction:row;\n    }\n    #uc_post_grid_elementor_ee22ce6.ue-list-view .uc_post_grid_style_one_item > div{\n     width:50%;\n    }\n   \n    #uc_post_grid_elementor_ee22ce6.ue-list-view .uc_content    {\n      display:flex;\n      flex-direction:column;\n      justify-content:center;\n    }\n \n\/*  for grid\/list layout switcher*\/\n\n#uc_post_grid_elementor_ee22ce6 .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_ee22ce6 .ue-grid-item-meta-data{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_post_grid_elementor_ee22ce6 .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor_ee22ce6 .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_ee22ce6 .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor_ee22ce6 .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n#uc_post_grid_elementor_ee22ce6 .uc_btn_inner{\n  display:inline-flex;\n  align-items:center;\n  pointer-events:none;\n}\n\n#uc_post_grid_elementor_ee22ce6 .uc_btn_inner svg{\n  width:1em;\n  height:1em;\n}\n#uc_post_grid_elementor_ee22ce6 .ue_p_title{\n  pointer-events:none;\n}\n  #uc_post_grid_elementor_ee22ce6 .ue_post_full_link{\n    position:absolute;\n    width:100%;\n    height:100%;\n    top:0;\n    left:0;\n    z-index: 10;\n  }\n\n\n#uc_post_grid_elementor_ee22ce6 .uc_content_inner{\n  width: 100%;\n}\n\n\n#uc_post_grid_elementor_ee22ce6 .view-switcher-button{\n  display: flex;\n  align-items: center;\n}\n\n#uc_post_grid_elementor_ee22ce6 .view-switcher-icon{\n  display: flex;\n  align-items: center;\n  line-height: 1;\n  cursor: pointer;\n  transition: all .3s ease;\n}\n\n#uc_post_grid_elementor_ee22ce6 .view-switcher-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_post_grid_elementor_ee22ce6 .view-switcher-icon.ue-hidden{\n  display: none;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item1 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item2 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item3 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item4 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item5 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item6 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item7 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item8 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item9 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_ee22ce6_item10 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n<\/style>\n\n<div id=\"uc_post_grid_elementor_ee22ce6\" class=\"uc_post_grid_style_one uc-filterable-grid \"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:10,&quot;total_posts&quot;:10,&quot;page&quot;:1,&quot;num_pages&quot;:1,&quot;woo&quot;:true}' >\n  \t\n  <div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper ue-woo-grid\">\n    \n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item1\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/rotary-control-ball-valves\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/Rotary_control_ball_valves-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/Rotary_control_ball_valves-768x768.webp\" alt=\"Rotary Control Ball valves\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/rotary-control-ball-valves\/' target=\"_self\"><div class=\"ue_p_title\">Rotary control ball valves<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-RCBV-002<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/rotary-control-ball-valves\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item2\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/adjustable-angle-choke-control-valves\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/product_image-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/product_image-768x768.webp\" alt=\"Adjustable angle choke control valves\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/modulating-control-valves\/\" class=\"control-valves\">Modulating Control Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/adjustable-angle-choke-control-valves\/' target=\"_self\"><div class=\"ue_p_title\">Adjustable angle choke control valves<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-AACV-001<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/adjustable-angle-choke-control-valves\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item3\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/intermittent-boiler-blowdown-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Intermittent-Boiler-Blowdown-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Intermittent-Boiler-Blowdown-Valve-768x768.webp\" alt=\"Intermittent Boiler Blowdown Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/pneumatic-on-off-specialty-valves\/\" class=\"control-valves\">Pneumatic On\/Off &amp; Specialty Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/intermittent-boiler-blowdown-valve\/' target=\"_self\"><div class=\"ue_p_title\">Intermittent Boiler Blowdown Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-BD80<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/intermittent-boiler-blowdown-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item4\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/pneumatic-globe-stop-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Pneumatic-Globe-Stop-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Pneumatic-Globe-Stop-Valve-768x768.webp\" alt=\"Pneumatic Globe Stop Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/pneumatic-on-off-specialty-valves\/\" class=\"control-valves\">Pneumatic On\/Off &amp; Specialty Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/pneumatic-globe-stop-valve\/' target=\"_self\"><div class=\"ue_p_title\">Pneumatic Globe Stop Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-SO20<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/pneumatic-globe-stop-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item5\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/3-way-self-acting-temperature-regulator\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/3-Way-Self-Acting-Temperature-Regulator-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/3-Way-Self-Acting-Temperature-Regulator-768x768.webp\" alt=\"3-Way Self-Acting Temperature Regulator\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/self-acting-regulators\/\" class=\"control-valves\">Self-Acting Regulators<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/3-way-self-acting-temperature-regulator\/' target=\"_self\"><div class=\"ue_p_title\">3-Way Self-Acting Temperature Regulator<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CDR-TR73<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/3-way-self-acting-temperature-regulator\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item6\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/self-acting-temperature-regulator\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Self-Acting-Temperature-Regulator-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Self-Acting-Temperature-Regulator-768x768.webp\" alt=\"Self-Acting Temperature Regulator\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/self-acting-regulators\/\" class=\"control-valves\">Self-Acting Regulators<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/self-acting-temperature-regulator\/' target=\"_self\"><div class=\"ue_p_title\">Self-Acting Temperature Regulator<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CDR-TR70<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/self-acting-temperature-regulator\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item7\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/direct-acting-pressure-reducing-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Direct-Acting-Pressure-Reducing-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Direct-Acting-Pressure-Reducing-Valve-768x768.webp\" alt=\"Direct-Acting Pressure Reducing Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/self-acting-regulators\/\" class=\"control-valves\">Self-Acting Regulators<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/direct-acting-pressure-reducing-valve\/' target=\"_self\"><div class=\"ue_p_title\">Direct-Acting Pressure Reducing Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CDR-PR40<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/direct-acting-pressure-reducing-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item8\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/3-way-mixing-diverting-control-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/3-Way-Mixing-Diverting-Control-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/3-Way-Mixing-Diverting-Control-Valve-768x768.webp\" alt=\"3-Way Mixing &amp; Diverting Control Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/modulating-control-valves\/\" class=\"control-valves\">Modulating Control Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/3-way-mixing-diverting-control-valve\/' target=\"_self\"><div class=\"ue_p_title\">3-Way Mixing &amp; Diverting Control Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVC-300M<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/3-way-mixing-diverting-control-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item9\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/severe-service-ansi-control-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Severe-Service-ANSI-Control-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Severe-Service-ANSI-Control-Valve-768x768.webp\" alt=\"Severe Service ANSI Control Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/modulating-control-valves\/\" class=\"control-valves\">Modulating Control Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/severe-service-ansi-control-valve\/' target=\"_self\"><div class=\"ue_p_title\">Severe Service ANSI Control Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVC-900A<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/severe-service-ansi-control-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_ee22ce6_item10\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-globe-control-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Globe-Control-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Globe-Control-Valve-768x768.webp\" alt=\"General-Purpose Globe Control Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/control-valves\/\" class=\"control-valves\">Control Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/modulating-control-valves\/\" class=\"control-valves\">Modulating Control Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-globe-control-valve\/' target=\"_self\"><div class=\"ue_p_title\">General-Purpose Globe Control Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVC-100<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-globe-control-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n  <\/div>\n<\/div>\n\n  <div id=\"uc_post_grid_elementor_ee22ce6_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n<!-- end Post Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2074724182\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2074724182\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-8e3d9af e-con-full e-flex e-con e-child\" data-id=\"8e3d9af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe382f elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"cbe382f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Grid -->\n\n<style>\/* widget: Post Grid *\/\n\n\r\n@keyframes uc_post_grid_elementor_cbe382f__item-animation {\r\n  0% {\r\n            \r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            \r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_cbe382f .ue-item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_cbe382f .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_post_grid_elementor_cbe382f .uc-entrance-animate {\r\n\tanimation: uc_post_grid_elementor_cbe382f__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_post_grid_elementor_cbe382f{\n  min-height: 1px;\n}\n\n#uc_post_grid_elementor_cbe382f.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n#uc_post_grid_elementor_cbe382f .uc_post_grid_style_one_item{\n  position:relative;\n}\n\n#uc_post_grid_elementor_cbe382f .uc_post_image{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor_cbe382f .uc_post_image img{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\t\n\n#uc_post_grid_elementor_cbe382f .uc_post_image_overlay{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_cbe382f .uc_more_btn-custom-field{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_cbe382f .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_grid_elementor_cbe382f .ue-grid-item-posttype{\n  display:inline-block;\n  position: relative;\n  z-index: 1;\n}\n\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor_cbe382f.uc_post_grid_style_one.ue-list-view .uc_content{\n flex-grow:1;\n}\n\n\n  #uc_post_grid_elementor_cbe382f:not(.ue-list-view) .ue_post_grid_item{\n    display:flex;\n    flex-direction:column;\n  }\n  \n  #uc_post_grid_elementor_cbe382f.uc_post_grid_style_one:not(.ue-list-view) .uc_content{\n   flex-grow:1;\n  }\n\n  #uc_post_grid_elementor_cbe382f.uc_post_grid_style_one .uc_content > div{\n    height:100%;\n    display:flex;\n    flex-direction:column;\n      }\n\n  \n\n\n\n\n\n\n\n\n\n\n\n\n\/*  for grid\/list layout switcher*\/\n\t#uc_post_grid_elementor_cbe382f.ue-list-view .uc_post_grid_style_one_item {\n     display:flex;  \n     flex-direction:row;\n    }\n    #uc_post_grid_elementor_cbe382f.ue-list-view .uc_post_grid_style_one_item > div{\n     width:50%;\n    }\n   \n    #uc_post_grid_elementor_cbe382f.ue-list-view .uc_content    {\n      display:flex;\n      flex-direction:column;\n      justify-content:center;\n    }\n \n\/*  for grid\/list layout switcher*\/\n\n#uc_post_grid_elementor_cbe382f .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_cbe382f .ue-grid-item-meta-data{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_post_grid_elementor_cbe382f .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor_cbe382f .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_cbe382f .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor_cbe382f .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n#uc_post_grid_elementor_cbe382f .uc_btn_inner{\n  display:inline-flex;\n  align-items:center;\n  pointer-events:none;\n}\n\n#uc_post_grid_elementor_cbe382f .uc_btn_inner svg{\n  width:1em;\n  height:1em;\n}\n#uc_post_grid_elementor_cbe382f .ue_p_title{\n  pointer-events:none;\n}\n  #uc_post_grid_elementor_cbe382f .ue_post_full_link{\n    position:absolute;\n    width:100%;\n    height:100%;\n    top:0;\n    left:0;\n    z-index: 10;\n  }\n\n\n#uc_post_grid_elementor_cbe382f .uc_content_inner{\n  width: 100%;\n}\n\n\n#uc_post_grid_elementor_cbe382f .view-switcher-button{\n  display: flex;\n  align-items: center;\n}\n\n#uc_post_grid_elementor_cbe382f .view-switcher-icon{\n  display: flex;\n  align-items: center;\n  line-height: 1;\n  cursor: pointer;\n  transition: all .3s ease;\n}\n\n#uc_post_grid_elementor_cbe382f .view-switcher-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_post_grid_elementor_cbe382f .view-switcher-icon.ue-hidden{\n  display: none;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item1 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item2 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item3 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item4 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item5 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item6 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item7 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item8 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item9 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item10 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item11 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item12 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_cbe382f_item13 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n<\/style>\n\n<div id=\"uc_post_grid_elementor_cbe382f\" class=\"uc_post_grid_style_one uc-filterable-grid \"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:13,&quot;total_posts&quot;:13,&quot;page&quot;:1,&quot;num_pages&quot;:1,&quot;woo&quot;:true}' >\n  \t\n  <div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper ue-woo-grid\">\n    \n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item1\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/fluorine-lined-butterfly-valve-wafer-end\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/Fluorine-Lined-Butterfly-Valve-Wafer-End.png\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/Fluorine-Lined-Butterfly-Valve-Wafer-End.png\" alt=\"Fluorine Lined Butterfly Valve Wafer End\" width=\"500\" height=\"500\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/butterfly-valves\/\" class=\"butterfly-valves\">Butterfly Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"butterfly-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/fluorine-lined-butterfly-valve-wafer-end\/' target=\"_self\"><div class=\"ue_p_title\">Fluorine Lined Butterfly Valve Wafer End<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  <\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/fluorine-lined-butterfly-valve-wafer-end\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item2\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/titanium-high-performance-butterfly-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/04\/WechatIMG2666-removebg-preview.png\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/04\/WechatIMG2666-removebg-preview.png\" alt=\"Titanium High Performance Butterfly Valve\" width=\"500\" height=\"500\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/butterfly-valves\/\" class=\"butterfly-valves\">Butterfly Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"butterfly-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/titanium-high-performance-butterfly-valve\/' target=\"_self\"><div class=\"ue_p_title\">Titanium High Performance Butterfly Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  <\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/titanium-high-performance-butterfly-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item3\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/y-type-strainer\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Y-Type-Strainer-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Y-Type-Strainer-768x768.webp\" alt=\"Y-Type Strainer\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"isolation-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/y-type-strainer\/' target=\"_self\"><div class=\"ue_p_title\">Y-Type Strainer<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-410<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/y-type-strainer\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item4\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/wafer-type-check-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Wafer-Type-Check-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Wafer-Type-Check-Valve-768x768.webp\" alt=\"Wafer Type Check Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/check-valves\/\" class=\"check-valves\">Check Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"check-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/wafer-type-check-valve\/' target=\"_self\"><div class=\"ue_p_title\">Wafer Type Check Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-310<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/wafer-type-check-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item5\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/high-performance-double-offset-butterfly-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/High-Performance-Double-Offset-Butterfly-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/High-Performance-Double-Offset-Butterfly-Valve-768x768.webp\" alt=\"High-Performance Double Offset Butterfly Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/butterfly-valves\/\" class=\"butterfly-valves\">Butterfly Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"butterfly-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/high-performance-double-offset-butterfly-valve\/' target=\"_self\"><div class=\"ue_p_title\">High-Performance Double Offset Butterfly Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-250<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/high-performance-double-offset-butterfly-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item6\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-centric-butterfly-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Centric-Butterfly-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Centric-Butterfly-Valve-768x768.webp\" alt=\"General-Purpose Centric Butterfly Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/butterfly-valves\/\" class=\"butterfly-valves\">Butterfly Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"butterfly-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-centric-butterfly-valve\/' target=\"_self\"><div class=\"ue_p_title\">General-Purpose Centric Butterfly Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-210<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-centric-butterfly-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item7\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/corrosion-resistant-bellows-seal-globe-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Corrosion-Resistant-Bellows-Seal-Globe-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Corrosion-Resistant-Bellows-Seal-Globe-Valve-768x768.webp\" alt=\"Corrosion-Resistant Bellows Seal Globe Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"isolation-valves\">Isolation Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/stop-valves\/\" class=\"isolation-valves\">Stop Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/corrosion-resistant-bellows-seal-globe-valve\/' target=\"_self\"><div class=\"ue_p_title\">Corrosion-Resistant Bellows Seal Globe Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-180<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/corrosion-resistant-bellows-seal-globe-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item8\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/high-temperature-bellows-seal-globe-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/High-Temperature-Bellows-Seal-Globe-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/High-Temperature-Bellows-Seal-Globe-Valve-768x768.webp\" alt=\"High-Temperature Bellows Seal Globe Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"isolation-valves\">Isolation Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/stop-valves\/\" class=\"isolation-valves\">Stop Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/high-temperature-bellows-seal-globe-valve\/' target=\"_self\"><div class=\"ue_p_title\">High-Temperature Bellows Seal Globe Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-150<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/high-temperature-bellows-seal-globe-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item9\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/soft-seated-globe-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Soft-Seated-Globe-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Soft-Seated-Globe-Valve-768x768.webp\" alt=\"Soft-Seated Globe Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"isolation-valves\">Isolation Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/stop-valves\/\" class=\"isolation-valves\">Stop Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/soft-seated-globe-valve\/' target=\"_self\"><div class=\"ue_p_title\">Soft-Seated Globe Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-120<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/soft-seated-globe-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item10\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-gland-seal-globe-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Gland-Seal-Globe-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Gland-Seal-Globe-Valve-768x768.webp\" alt=\"General-Purpose Gland Seal Globe Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"isolation-valves\">Isolation Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/stop-valves\/\" class=\"isolation-valves\">Stop Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-gland-seal-globe-valve\/' target=\"_self\"><div class=\"ue_p_title\">General-Purpose Gland Seal Globe Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-110<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-gland-seal-globe-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item11\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/cryogenic-six-eccentric-butterfly-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Cryogenic-Six-Eccentric-Butterfly-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Cryogenic-Six-Eccentric-Butterfly-Valve-768x768.webp\" alt=\"Cryogenic Six-Eccentric Butterfly Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/six-eccentric-hexa-butterfly-valves\/\" class=\"six-eccentric-hexa-butterfly-valves\">(Six-Eccentric) Hexa Butterfly Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"six-eccentric-hexa-butterfly-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/cryogenic-six-eccentric-butterfly-valve\/' target=\"_self\"><div class=\"ue_p_title\">Cryogenic Six-Eccentric Butterfly Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-290C<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/cryogenic-six-eccentric-butterfly-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item12\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/next-gen-six-eccentric-butterfly-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Next-Gen-Six-Eccentric-Butterfly-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Next-Gen-Six-Eccentric-Butterfly-Valve-768x768.webp\" alt=\"Next-Gen Six-Eccentric Butterfly Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/six-eccentric-hexa-butterfly-valves\/\" class=\"six-eccentric-hexa-butterfly-valves\">(Six-Eccentric) Hexa Butterfly Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"six-eccentric-hexa-butterfly-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/next-gen-six-eccentric-butterfly-valve\/' target=\"_self\"><div class=\"ue_p_title\">Next-Gen Six-Eccentric Butterfly Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-290<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/next-gen-six-eccentric-butterfly-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_cbe382f_item13\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/ultra-high-pressure-triple-offset-butterfly-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Ultra-High-Pressure-Triple-Offset-Butterfly-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Ultra-High-Pressure-Triple-Offset-Butterfly-Valve-768x768.webp\" alt=\"Ultra High-Pressure Triple Offset Butterfly Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/six-eccentric-hexa-butterfly-valves\/\" class=\"six-eccentric-hexa-butterfly-valves\">(Six-Eccentric) Hexa Butterfly Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/isolation-valves\/\" class=\"six-eccentric-hexa-butterfly-valves\">Isolation Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/ultra-high-pressure-triple-offset-butterfly-valve\/' target=\"_self\"><div class=\"ue_p_title\">Ultra High-Pressure Triple Offset Butterfly Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-288<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/ultra-high-pressure-triple-offset-butterfly-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n  <\/div>\n<\/div>\n\n  <div id=\"uc_post_grid_elementor_cbe382f_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n<!-- end Post Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2074724183\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2074724183\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-7ce9c18 e-con-full e-flex e-con e-child\" data-id=\"7ce9c18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-898d188 elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"898d188\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Grid -->\n\n<style>\/* widget: Post Grid *\/\n\n\r\n@keyframes uc_post_grid_elementor_898d188__item-animation {\r\n  0% {\r\n            \r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            \r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_898d188 .ue-item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_898d188 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_post_grid_elementor_898d188 .uc-entrance-animate {\r\n\tanimation: uc_post_grid_elementor_898d188__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_post_grid_elementor_898d188{\n  min-height: 1px;\n}\n\n#uc_post_grid_elementor_898d188.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n#uc_post_grid_elementor_898d188 .uc_post_grid_style_one_item{\n  position:relative;\n}\n\n#uc_post_grid_elementor_898d188 .uc_post_image{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor_898d188 .uc_post_image img{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\t\n\n#uc_post_grid_elementor_898d188 .uc_post_image_overlay{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_898d188 .uc_more_btn-custom-field{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_898d188 .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_grid_elementor_898d188 .ue-grid-item-posttype{\n  display:inline-block;\n  position: relative;\n  z-index: 1;\n}\n\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor_898d188.uc_post_grid_style_one.ue-list-view .uc_content{\n flex-grow:1;\n}\n\n\n  #uc_post_grid_elementor_898d188:not(.ue-list-view) .ue_post_grid_item{\n    display:flex;\n    flex-direction:column;\n  }\n  \n  #uc_post_grid_elementor_898d188.uc_post_grid_style_one:not(.ue-list-view) .uc_content{\n   flex-grow:1;\n  }\n\n  #uc_post_grid_elementor_898d188.uc_post_grid_style_one .uc_content > div{\n    height:100%;\n    display:flex;\n    flex-direction:column;\n      }\n\n  \n\n\n\n\n\n\n\n\n\n\n\n\n\/*  for grid\/list layout switcher*\/\n\t#uc_post_grid_elementor_898d188.ue-list-view .uc_post_grid_style_one_item {\n     display:flex;  \n     flex-direction:row;\n    }\n    #uc_post_grid_elementor_898d188.ue-list-view .uc_post_grid_style_one_item > div{\n     width:50%;\n    }\n   \n    #uc_post_grid_elementor_898d188.ue-list-view .uc_content    {\n      display:flex;\n      flex-direction:column;\n      justify-content:center;\n    }\n \n\/*  for grid\/list layout switcher*\/\n\n#uc_post_grid_elementor_898d188 .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_898d188 .ue-grid-item-meta-data{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_post_grid_elementor_898d188 .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor_898d188 .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_898d188 .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor_898d188 .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n#uc_post_grid_elementor_898d188 .uc_btn_inner{\n  display:inline-flex;\n  align-items:center;\n  pointer-events:none;\n}\n\n#uc_post_grid_elementor_898d188 .uc_btn_inner svg{\n  width:1em;\n  height:1em;\n}\n#uc_post_grid_elementor_898d188 .ue_p_title{\n  pointer-events:none;\n}\n  #uc_post_grid_elementor_898d188 .ue_post_full_link{\n    position:absolute;\n    width:100%;\n    height:100%;\n    top:0;\n    left:0;\n    z-index: 10;\n  }\n\n\n#uc_post_grid_elementor_898d188 .uc_content_inner{\n  width: 100%;\n}\n\n\n#uc_post_grid_elementor_898d188 .view-switcher-button{\n  display: flex;\n  align-items: center;\n}\n\n#uc_post_grid_elementor_898d188 .view-switcher-icon{\n  display: flex;\n  align-items: center;\n  line-height: 1;\n  cursor: pointer;\n  transition: all .3s ease;\n}\n\n#uc_post_grid_elementor_898d188 .view-switcher-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_post_grid_elementor_898d188 .view-switcher-icon.ue-hidden{\n  display: none;\n}\n\n\n#uc_post_grid_elementor_898d188_item1 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_898d188_item2 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_898d188_item3 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_898d188_item4 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n<\/style>\n\n<div id=\"uc_post_grid_elementor_898d188\" class=\"uc_post_grid_style_one uc-filterable-grid \"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:4,&quot;total_posts&quot;:4,&quot;page&quot;:1,&quot;num_pages&quot;:1,&quot;woo&quot;:true}' >\n  \t\n  <div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper ue-woo-grid\">\n    \n\n\n\n\n<div id=\"uc_post_grid_elementor_898d188_item1\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-full-lift-safety-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Full-Lift-Safety-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/General-Purpose-Full-Lift-Safety-Valve-768x768.webp\" alt=\"General-Purpose Full-Lift Safety Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/high-flow-safety-valves\/\" class=\"high-flow-safety-valves\">High-Flow Safety Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/safety-relief-valves\/\" class=\"high-flow-safety-valves\">Safety Relief Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-full-lift-safety-valve\/' target=\"_self\"><div class=\"ue_p_title\">General-Purpose Full Lift Safety Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CSV-510<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/general-purpose-full-lift-safety-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_898d188_item2\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/api-526-full-nozzle-safety-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/API-526-Full-Nozzle-Safety-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/API-526-Full-Nozzle-Safety-Valve-768x768.webp\" alt=\"API 526 Full-Nozzle Safety Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/high-flow-safety-valves\/\" class=\"high-flow-safety-valves\">High-Flow Safety Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/safety-relief-valves\/\" class=\"high-flow-safety-valves\">Safety Relief Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/api-526-full-nozzle-safety-valve\/' target=\"_self\"><div class=\"ue_p_title\">API 526 Full-Nozzle Safety Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CSV-580<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/api-526-full-nozzle-safety-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_898d188_item3\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/asme-standard-full-lift-safety-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/ASME-Standard-Full-Lift-Safety-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/ASME-Standard-Full-Lift-Safety-Valve-768x768.webp\" alt=\"ASME Standard Full-Lift Safety Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/safety-relief-valves\/\" class=\"safety-relief-valves\">Safety Relief Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/standard-flow-safety-valves\/\" class=\"safety-relief-valves\">Standard-Flow Safety Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/asme-standard-full-lift-safety-valve\/' target=\"_self\"><div class=\"ue_p_title\">ASME Standard Full-Lift Safety Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CSV-530<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/asme-standard-full-lift-safety-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_898d188_item4\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/threaded-connection-safety-valve\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Threaded-Connection-Safety-Valve-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Threaded-Connection-Safety-Valve-768x768.webp\" alt=\"Threaded Connection Safety Valve\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/safety-relief-valves\/\" class=\"safety-relief-valves\">Safety Relief Valves<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/standard-flow-safety-valves\/\" class=\"safety-relief-valves\">Standard-Flow Safety Valves<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/threaded-connection-safety-valve\/' target=\"_self\"><div class=\"ue_p_title\">Threaded Connection Safety Valve<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CSV-515<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/threaded-connection-safety-valve\/' target=\"_self\"><\/a>      \n<\/div>\n\n  <\/div>\n<\/div>\n\n  <div id=\"uc_post_grid_elementor_898d188_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n<!-- end Post Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2074724184\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2074724184\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-b89f644 e-flex e-con-boxed e-con e-child\" data-id=\"b89f644\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a29eecf elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"a29eecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Grid -->\n\n<style>\/* widget: Post Grid *\/\n\n\r\n@keyframes uc_post_grid_elementor_a29eecf__item-animation {\r\n  0% {\r\n            \r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            \r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_a29eecf .ue-item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_a29eecf .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_post_grid_elementor_a29eecf .uc-entrance-animate {\r\n\tanimation: uc_post_grid_elementor_a29eecf__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_post_grid_elementor_a29eecf{\n  min-height: 1px;\n}\n\n#uc_post_grid_elementor_a29eecf.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n#uc_post_grid_elementor_a29eecf .uc_post_grid_style_one_item{\n  position:relative;\n}\n\n#uc_post_grid_elementor_a29eecf .uc_post_image{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor_a29eecf .uc_post_image img{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\t\n\n#uc_post_grid_elementor_a29eecf .uc_post_image_overlay{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_a29eecf .uc_more_btn-custom-field{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_a29eecf .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_grid_elementor_a29eecf .ue-grid-item-posttype{\n  display:inline-block;\n  position: relative;\n  z-index: 1;\n}\n\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor_a29eecf.uc_post_grid_style_one.ue-list-view .uc_content{\n flex-grow:1;\n}\n\n\n  #uc_post_grid_elementor_a29eecf:not(.ue-list-view) .ue_post_grid_item{\n    display:flex;\n    flex-direction:column;\n  }\n  \n  #uc_post_grid_elementor_a29eecf.uc_post_grid_style_one:not(.ue-list-view) .uc_content{\n   flex-grow:1;\n  }\n\n  #uc_post_grid_elementor_a29eecf.uc_post_grid_style_one .uc_content > div{\n    height:100%;\n    display:flex;\n    flex-direction:column;\n      }\n\n  \n\n\n\n\n\n\n\n\n\n\n\n\n\/*  for grid\/list layout switcher*\/\n\t#uc_post_grid_elementor_a29eecf.ue-list-view .uc_post_grid_style_one_item {\n     display:flex;  \n     flex-direction:row;\n    }\n    #uc_post_grid_elementor_a29eecf.ue-list-view .uc_post_grid_style_one_item > div{\n     width:50%;\n    }\n   \n    #uc_post_grid_elementor_a29eecf.ue-list-view .uc_content    {\n      display:flex;\n      flex-direction:column;\n      justify-content:center;\n    }\n \n\/*  for grid\/list layout switcher*\/\n\n#uc_post_grid_elementor_a29eecf .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_a29eecf .ue-grid-item-meta-data{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_post_grid_elementor_a29eecf .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor_a29eecf .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_a29eecf .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor_a29eecf .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n#uc_post_grid_elementor_a29eecf .uc_btn_inner{\n  display:inline-flex;\n  align-items:center;\n  pointer-events:none;\n}\n\n#uc_post_grid_elementor_a29eecf .uc_btn_inner svg{\n  width:1em;\n  height:1em;\n}\n#uc_post_grid_elementor_a29eecf .ue_p_title{\n  pointer-events:none;\n}\n  #uc_post_grid_elementor_a29eecf .ue_post_full_link{\n    position:absolute;\n    width:100%;\n    height:100%;\n    top:0;\n    left:0;\n    z-index: 10;\n  }\n\n\n#uc_post_grid_elementor_a29eecf .uc_content_inner{\n  width: 100%;\n}\n\n\n#uc_post_grid_elementor_a29eecf .view-switcher-button{\n  display: flex;\n  align-items: center;\n}\n\n#uc_post_grid_elementor_a29eecf .view-switcher-icon{\n  display: flex;\n  align-items: center;\n  line-height: 1;\n  cursor: pointer;\n  transition: all .3s ease;\n}\n\n#uc_post_grid_elementor_a29eecf .view-switcher-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_post_grid_elementor_a29eecf .view-switcher-icon.ue-hidden{\n  display: none;\n}\n\n\n#uc_post_grid_elementor_a29eecf_item1 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_a29eecf_item2 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n<\/style>\n\n<div id=\"uc_post_grid_elementor_a29eecf\" class=\"uc_post_grid_style_one uc-filterable-grid \"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:2,&quot;total_posts&quot;:2,&quot;page&quot;:1,&quot;num_pages&quot;:1,&quot;woo&quot;:true}' >\n  \t\n  <div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper ue-woo-grid\">\n    \n\n\n\n\n<div id=\"uc_post_grid_elementor_a29eecf_item1\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/forged-steam-trap\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/F-_Forged_Steam_Trap-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/05\/F-_Forged_Steam_Trap-768x768.webp\" alt=\"forgerd steam trap\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/steam-traps\/\" class=\"steam-traps\">Steam Traps<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/forged-steam-trap\/' target=\"_self\"><div class=\"ue_p_title\">Forged Steam Trap<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CVS-VALVE-010<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/forged-steam-trap\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_a29eecf_item2\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/mechanical-steam-trap\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Mechanical-Steam-Trap-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Mechanical-Steam-Trap-768x768.webp\" alt=\"Mechanical Steam Trap\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/steam-traps\/\" class=\"steam-traps\">Steam Traps<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/mechanical-steam-trap\/' target=\"_self\"><div class=\"ue_p_title\">Mechanical Steam Trap<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CST-610<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/mechanical-steam-trap\/' target=\"_self\"><\/a>      \n<\/div>\n\n  <\/div>\n<\/div>\n\n  <div id=\"uc_post_grid_elementor_a29eecf_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n<!-- end Post Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2074724185\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2074724185\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\" elementor-element elementor-element-a10e0f7 e-flex e-con-boxed e-con e-child\" data-id=\"a10e0f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bbf2c8 elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"4bbf2c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Grid -->\n\n<style>\/* widget: Post Grid *\/\n\n\r\n@keyframes uc_post_grid_elementor_4bbf2c8__item-animation {\r\n  0% {\r\n            \r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            \r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_4bbf2c8 .ue-item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_4bbf2c8 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_post_grid_elementor_4bbf2c8 .uc-entrance-animate {\r\n\tanimation: uc_post_grid_elementor_4bbf2c8__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_post_grid_elementor_4bbf2c8{\n  min-height: 1px;\n}\n\n#uc_post_grid_elementor_4bbf2c8.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n#uc_post_grid_elementor_4bbf2c8 .uc_post_grid_style_one_item{\n  position:relative;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .uc_post_image{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .uc_post_image img{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\t\n\n#uc_post_grid_elementor_4bbf2c8 .uc_post_image_overlay{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .uc_more_btn-custom-field{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .ue-grid-item-posttype{\n  display:inline-block;\n  position: relative;\n  z-index: 1;\n}\n\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor_4bbf2c8.uc_post_grid_style_one.ue-list-view .uc_content{\n flex-grow:1;\n}\n\n\n  #uc_post_grid_elementor_4bbf2c8:not(.ue-list-view) .ue_post_grid_item{\n    display:flex;\n    flex-direction:column;\n  }\n  \n  #uc_post_grid_elementor_4bbf2c8.uc_post_grid_style_one:not(.ue-list-view) .uc_content{\n   flex-grow:1;\n  }\n\n  #uc_post_grid_elementor_4bbf2c8.uc_post_grid_style_one .uc_content > div{\n    height:100%;\n    display:flex;\n    flex-direction:column;\n      }\n\n  \n\n\n\n\n\n\n\n\n\n\n\n\n\/*  for grid\/list layout switcher*\/\n\t#uc_post_grid_elementor_4bbf2c8.ue-list-view .uc_post_grid_style_one_item {\n     display:flex;  \n     flex-direction:row;\n    }\n    #uc_post_grid_elementor_4bbf2c8.ue-list-view .uc_post_grid_style_one_item > div{\n     width:50%;\n    }\n   \n    #uc_post_grid_elementor_4bbf2c8.ue-list-view .uc_content    {\n      display:flex;\n      flex-direction:column;\n      justify-content:center;\n    }\n \n\/*  for grid\/list layout switcher*\/\n\n#uc_post_grid_elementor_4bbf2c8 .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .ue-grid-item-meta-data{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .uc_btn_inner{\n  display:inline-flex;\n  align-items:center;\n  pointer-events:none;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .uc_btn_inner svg{\n  width:1em;\n  height:1em;\n}\n#uc_post_grid_elementor_4bbf2c8 .ue_p_title{\n  pointer-events:none;\n}\n  #uc_post_grid_elementor_4bbf2c8 .ue_post_full_link{\n    position:absolute;\n    width:100%;\n    height:100%;\n    top:0;\n    left:0;\n    z-index: 10;\n  }\n\n\n#uc_post_grid_elementor_4bbf2c8 .uc_content_inner{\n  width: 100%;\n}\n\n\n#uc_post_grid_elementor_4bbf2c8 .view-switcher-button{\n  display: flex;\n  align-items: center;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .view-switcher-icon{\n  display: flex;\n  align-items: center;\n  line-height: 1;\n  cursor: pointer;\n  transition: all .3s ease;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .view-switcher-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_post_grid_elementor_4bbf2c8 .view-switcher-icon.ue-hidden{\n  display: none;\n}\n\n\n#uc_post_grid_elementor_4bbf2c8_item1 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_4bbf2c8_item2 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_4bbf2c8_item3 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_4bbf2c8_item4 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n<\/style>\n\n<div id=\"uc_post_grid_elementor_4bbf2c8\" class=\"uc_post_grid_style_one \"  >\n  \t\n  <div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper ue-woo-grid\">\n    \n\n\n\n\n<div id=\"uc_post_grid_elementor_4bbf2c8_item1\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/smart-electric-actuator\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Smart-Electric-Actuator-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Smart-Electric-Actuator-768x768.webp\" alt=\"Smart Electric Actuator\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/actuation\/\" class=\"actuation\">Actuation<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/electric-actuators\/\" class=\"actuation\">Electric Actuators<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/smart-electric-actuator\/' target=\"_self\"><div class=\"ue_p_title\">Smart Electric Actuator<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CAA-860<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/smart-electric-actuator\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_4bbf2c8_item2\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/industrial-grade-electric-actuator\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Industrial-Grade-Electric-Actuator-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Industrial-Grade-Electric-Actuator-768x768.webp\" alt=\"Industrial Grade Electric Actuator\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/actuation\/\" class=\"actuation\">Actuation<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/electric-actuators\/\" class=\"actuation\">Electric Actuators<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/industrial-grade-electric-actuator\/' target=\"_self\"><div class=\"ue_p_title\">Industrial Grade Electric Actuator<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CAA-850<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/industrial-grade-electric-actuator\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_4bbf2c8_item3\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/digital-electro-pneumatic-valve-positioner\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Digital-Electro-Pneumatic-Valve-Positioner-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Digital-Electro-Pneumatic-Valve-Positioner-768x768.webp\" alt=\"Digital Electro-Pneumatic Valve Positioner\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/pneumatic-actuators\/\" class=\"pneumatic-actuators\">Pneumatic Actuators<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/digital-electro-pneumatic-valve-positioner\/' target=\"_self\"><div class=\"ue_p_title\">Digital Electro-Pneumatic Valve Positioner<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CAA-815<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/digital-electro-pneumatic-valve-positioner\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_4bbf2c8_item4\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/pneumatic-diaphragm-actuator\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Pneumatic-Diaphragm-Actuator-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Pneumatic-Diaphragm-Actuator-768x768.webp\" alt=\"Pneumatic Diaphragm Actuator\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/actuation\/\" class=\"actuation\">Actuation<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/pneumatic-actuators\/\" class=\"actuation\">Pneumatic Actuators<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/pneumatic-diaphragm-actuator\/' target=\"_self\"><div class=\"ue_p_title\">Pneumatic Diaphragm Actuator<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CAA-810<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/pneumatic-diaphragm-actuator\/' target=\"_self\"><\/a>      \n<\/div>\n\n  <\/div>\n<\/div>\n\n  <div id=\"uc_post_grid_elementor_4bbf2c8_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n<!-- end Post Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2074724186\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2074724186\" data-tab-index=\"6\" style=\"--n-tabs-title-order: 6;\" class=\" elementor-element elementor-element-05c2ed3 e-flex e-con-boxed e-con e-child\" data-id=\"05c2ed3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc3a6e7 elementor-widget elementor-widget-ucaddon_post_grid\" data-id=\"fc3a6e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ucaddon_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Post Grid -->\n\n<style>\/* widget: Post Grid *\/\n\n\r\n@keyframes uc_post_grid_elementor_fc3a6e7__item-animation {\r\n  0% {\r\n            \r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            \r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_fc3a6e7 .ue-item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_post_grid_elementor_fc3a6e7 .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_post_grid_elementor_fc3a6e7 .uc-entrance-animate {\r\n\tanimation: uc_post_grid_elementor_fc3a6e7__item-animation 0.6s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_post_grid_elementor_fc3a6e7{\n  min-height: 1px;\n}\n\n#uc_post_grid_elementor_fc3a6e7.uc_post_grid_style_one .uc_post_grid_style_one_wrap {\n   display:grid;\n}\n\n\n#uc_post_grid_elementor_fc3a6e7 .uc_post_grid_style_one_item{\n  position:relative;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .uc_post_image{\n  transition:0.3s;\n  position:relative;\n  overflow:hidden;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .uc_post_image img{\n  width:100%;\n  display:block;\n  transition:0.3s;\n}\n\n\t\n\n#uc_post_grid_elementor_fc3a6e7 .uc_post_image_overlay{\n  position:absolute;\n  top:0px;\n  left:0px;\n  height:100%;\n  width:100%;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .uc_more_btn-custom-field{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .uc_more_btn{\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n  transition:0.3s;\n}\n\n.ue-grid-item-category a{\n  display:inline-block;\n  font-size:10px;\n  position: relative;\n  z-index: 1;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .ue-grid-item-posttype{\n  display:inline-block;\n  position: relative;\n  z-index: 1;\n}\n\n\n.uc_post_title{\n  font-size:21px;\n}\n\n\n#uc_post_grid_elementor_fc3a6e7.uc_post_grid_style_one.ue-list-view .uc_content{\n flex-grow:1;\n}\n\n\n  #uc_post_grid_elementor_fc3a6e7:not(.ue-list-view) .ue_post_grid_item{\n    display:flex;\n    flex-direction:column;\n  }\n  \n  #uc_post_grid_elementor_fc3a6e7.uc_post_grid_style_one:not(.ue-list-view) .uc_content{\n   flex-grow:1;\n  }\n\n  #uc_post_grid_elementor_fc3a6e7.uc_post_grid_style_one .uc_content > div{\n    height:100%;\n    display:flex;\n    flex-direction:column;\n      }\n\n  \n\n\n\n\n\n\n\n\n\n\n\n\n\/*  for grid\/list layout switcher*\/\n\t#uc_post_grid_elementor_fc3a6e7.ue-list-view .uc_post_grid_style_one_item {\n     display:flex;  \n     flex-direction:row;\n    }\n    #uc_post_grid_elementor_fc3a6e7.ue-list-view .uc_post_grid_style_one_item > div{\n     width:50%;\n    }\n   \n    #uc_post_grid_elementor_fc3a6e7.ue-list-view .uc_content    {\n      display:flex;\n      flex-direction:column;\n      justify-content:center;\n    }\n \n\/*  for grid\/list layout switcher*\/\n\n#uc_post_grid_elementor_fc3a6e7 .ue-meta-data{  \n  display:flex !important;\n  flex-wrap: wrap;\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .ue-grid-item-meta-data{\n  display:inline-flex;\n  align-items:center;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .ue-grid-item-meta-data a{\n  color:inherit;\n}\n\n.ue-grid-item-meta-data{\n  font-size:12px;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .ue-grid-item-meta-data-icon{\n  line-height:1em;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .ue-grid-item-meta-data-icon svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .ue-debug-meta{\n  padding:10px;\n  border:1px solid red;\n  position:relative;\n  line-height:1.5em;\n  font-size:11px;\n  width:100%;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .uc_btn_inner{\n  display:inline-flex;\n  align-items:center;\n  pointer-events:none;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .uc_btn_inner svg{\n  width:1em;\n  height:1em;\n}\n#uc_post_grid_elementor_fc3a6e7 .ue_p_title{\n  pointer-events:none;\n}\n  #uc_post_grid_elementor_fc3a6e7 .ue_post_full_link{\n    position:absolute;\n    width:100%;\n    height:100%;\n    top:0;\n    left:0;\n    z-index: 10;\n  }\n\n\n#uc_post_grid_elementor_fc3a6e7 .uc_content_inner{\n  width: 100%;\n}\n\n\n#uc_post_grid_elementor_fc3a6e7 .view-switcher-button{\n  display: flex;\n  align-items: center;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .view-switcher-icon{\n  display: flex;\n  align-items: center;\n  line-height: 1;\n  cursor: pointer;\n  transition: all .3s ease;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .view-switcher-icon svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_post_grid_elementor_fc3a6e7 .view-switcher-icon.ue-hidden{\n  display: none;\n}\n\n\n#uc_post_grid_elementor_fc3a6e7_item1 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n#uc_post_grid_elementor_fc3a6e7_item2 [href=\"javascript:void(0)\"]{\n  cursor: unset;\n}\n\n\n<\/style>\n\n<div id=\"uc_post_grid_elementor_fc3a6e7\" class=\"uc_post_grid_style_one uc-filterable-grid \"  data-ajax='true'  data-filterbehave='ajax'  querydata='{&quot;count_posts&quot;:2,&quot;total_posts&quot;:2,&quot;page&quot;:1,&quot;num_pages&quot;:1,&quot;woo&quot;:true}' >\n  \t\n  <div class=\"uc_post_grid_style_one_wrap ue_post_grid uc-items-wrapper ue-woo-grid\">\n    \n\n\n\n\n<div id=\"uc_post_grid_elementor_fc3a6e7_item1\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/skid-mounted-condensate-recovery-station\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Skid-mounted-Condensate-Recovery-Station-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Skid-mounted-Condensate-Recovery-Station-768x768.webp\" alt=\"Skid-mounted Condensate Recovery Station\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/desuperheating-systems\/\" class=\"desuperheating-systems\">Desuperheating Systems<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/system-packages\/\" class=\"desuperheating-systems\">System Packages<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/skid-mounted-condensate-recovery-station\/' target=\"_self\"><div class=\"ue_p_title\">Skid-mounted Condensate Recovery Station<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CSY-210<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/skid-mounted-condensate-recovery-station\/' target=\"_self\"><\/a>      \n<\/div>\n\n\n\n\n\n<div id=\"uc_post_grid_elementor_fc3a6e7_item2\" class=\"uc_post_grid_style_one_item ue_post_grid_item ue-item \">\n  \n      <a class=\"uc_post_grid_style_one_image \" href='https:\/\/cartervalves.com\/nl\/product\/skid-mounted-steam-pressure-reducing-and-regulating-station\/' target=\"_self\">\n     <div class=\"uc_post_image\">\n       <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Skid-mounted-Steam-Pressure-Reducing-and-Regulating-Station-768x768.webp\"  src=\"https:\/\/cartervalves.com\/wp-content\/uploads\/2026\/02\/Skid-mounted-Steam-Pressure-Reducing-and-Regulating-Station-768x768.webp\" alt=\"Skid-mounted Steam Pressure Reducing and Regulating Station\" width=\"768\" height=\"768\">\n       <div class=\"uc_post_image_overlay\"><\/div>\n     <\/div>\n    <\/a>\n   \n  <div class=\"uc_content\">\n    <div class=\"uc_content_inner\">\n      <div class=\"uc_content-info-wrapper\" >\n                \n          \n              \n    <div class=\"ue-grid-item-category\">\n                        <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/desuperheating-systems\/\" class=\"desuperheating-systems\">Desuperheating Systems<\/a>\n                                <a href=\"https:\/\/cartervalves.com\/nl\/product-categories\/system-packages\/\" class=\"desuperheating-systems\">System Packages<\/a>\n                  <\/div>\n                      \n        <div class=\"uc_post_title\"><a class=\"\" href='https:\/\/cartervalves.com\/nl\/product\/skid-mounted-steam-pressure-reducing-and-regulating-station\/' target=\"_self\"><div class=\"ue_p_title\">Skid-mounted Steam Pressure Reducing and Regulating Station<\/div><\/a><\/div>\t\n                 \n          <div class=\"ue-meta-data\">\n            \n                \t    \n                \n        \n\t\n           \n          \t\t\n      \t\t\t\t\n\t  \t\t<div class=\"ue-grid-item-meta-data ue-grid-item-meta-data--one\"><span class=\"ue-grid-item-meta-data-icon\"><i class=''><\/i><\/span>  CSY-110<\/div>\n      \t\t\t\t\n                \n                \n                \n                \n    \t\t\t\n      \n            \n  <\/div>\t\n             \n                   \n                         \n                                              \n      <\/div>                      \n                            \n \t<\/div>  <\/div>      \n  <a class=\"ue_post_full_link \" href='https:\/\/cartervalves.com\/nl\/product\/skid-mounted-steam-pressure-reducing-and-regulating-station\/' target=\"_self\"><\/a>      \n<\/div>\n\n  <\/div>\n<\/div>\n\n  <div id=\"uc_post_grid_elementor_fc3a6e7_empty_message\" class=\"ue-no-posts-found\"  style=\"display:none\" >No posts found<\/div>\n\n<!-- end Post Grid -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6e6178 e-flex e-con-boxed e-con e-parent\" data-id=\"c6e6178\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b2a9615 e-con-full e-flex e-con e-child\" data-id=\"b2a9615\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71daebc elementor-widget elementor-widget-heading\" data-id=\"71daebc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We'd like to work with you<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c4e0fb elementor-widget elementor-widget-text-editor\" data-id=\"3c4e0fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Send us a message if you have any questions or request a quote. Our experts will give you a reply within 24 hours and help you select the right valve you want.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c420b7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6c420b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M493.4 24.6l-104-24c-11.3-2.6-22.9 3.3-27.5 13.9l-48 112c-4.2 9.8-1.4 21.3 6.9 28l60.6 49.6c-36 76.7-98.9 140.5-177.2 177.2l-49.6-60.6c-6.8-8.3-18.2-11.1-28-6.9l-112 48C3.9 366.5-2 378.1.6 389.4l24 104C27.1 504.2 36.7 512 48 512c256.1 0 464-207.5 464-464 0-11.2-7.7-20.9-18.6-23.4z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">400-998-3976<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-mail-bulk\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M160 448c-25.6 0-51.2-22.4-64-32-64-44.8-83.2-60.8-96-70.4V480c0 17.67 14.33 32 32 32h256c17.67 0 32-14.33 32-32V345.6c-12.8 9.6-32 25.6-96 70.4-12.8 9.6-38.4 32-64 32zm128-192H32c-17.67 0-32 14.33-32 32v16c25.6 19.2 22.4 19.2 115.2 86.4 9.6 6.4 28.8 25.6 44.8 25.6s35.2-19.2 44.8-22.4c92.8-67.2 89.6-67.2 115.2-86.4V288c0-17.67-14.33-32-32-32zm256-96H224c-17.67 0-32 14.33-32 32v32h96c33.21 0 60.59 25.42 63.71 57.82l.29-.22V416h192c17.67 0 32-14.33 32-32V192c0-17.67-14.33-32-32-32zm-32 128h-64v-64h64v64zm-352-96c0-35.29 28.71-64 64-64h224V32c0-17.67-14.33-32-32-32H96C78.33 0 64 14.33 64 32v192h96v-32z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@cartervalves.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-505d4ee e-con-full e-flex e-con e-child\" data-id=\"505d4ee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d802de fluentform-widget-submit-button-left fluentform-widget-submit-button-custom elementor-widget elementor-widget-fluent-form-widget\" data-id=\"1d802de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"fluent-form-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"fluentform-widget-wrapper fluentform-widget-align-default\">\n\n            \n            <div class='fluentform ff-default fluentform_wrapper_3 ffs_default_wrap'><form data-form_id=\"3\" id=\"fluentform_3\" class=\"frm-fluent-form fluent_form_3 ff-el-form-top ff_form_instance_3_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_3_1\" method=\"POST\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Contact Us<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='424' \/><input type=\"hidden\" id=\"_fluentform_3_fluentformnonce\" name=\"_fluentform_3_fluentformnonce\" value=\"8a658c3f06\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/nl\/wp-json\/wp\/v2\/pages\/424\" \/><div data-name=\"ff_cn_id_1\"  class='ff-t-container ff-column-container ff_columns_total_2 '><div class='ff-t-cell ff-t-column-1' style='flex-basis: 50%;'><div data-type=\"name-element\" data-name=\"names\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_names_first_name_' id='label_ff_3_names_first_name_' >Your Name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_3_names_first_name_\" class=\"ff-el-form-control\" placeholder=\"Call me...\" aria-invalid=\"false\" aria-required=true><\/div><\/div><\/div><\/div><\/div><\/div><div class='ff-t-cell ff-t-column-2' style='flex-basis: 50%;'><div data-type=\"name-element\" data-name=\"names_2\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_names_2_first_name_' id='label_ff_3_names_2_first_name_' >Phone<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names_2[first_name]\" id=\"ff_3_names_2_first_name_\" class=\"ff-el-form-control\" placeholder=\"Phone Number\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-type=\"name-element\" data-name=\"names_1\" class=\" ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell '><div class='ff-el-group ff-el-form-top'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_names_1_first_name_' id='label_ff_3_names_1_first_name_' >Company<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names_1[first_name]\" id=\"ff_3_names_1_first_name_\" class=\"ff-el-form-control\" placeholder=\"Company Name\" aria-invalid=\"false\" aria-required=false><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_3_email' id='label_ff_3_email' aria-label=\"Email\">Email<\/label><div class=\"ff-el-tooltip\" data-content=\"Note: We will reply to you as soon as we see it!\"><svg width=\"16\" height=\"16\" viewBox=\"0 0 25 25\"><path d=\"m329 393l0-46c0-2-1-4-2-6-2-2-4-3-7-3l-27 0 0-146c0-3-1-5-3-7-2-1-4-2-7-2l-91 0c-3 0-5 1-7 2-1 2-2 4-2 7l0 46c0 2 1 5 2 6 2 2 4 3 7 3l27 0 0 91-27 0c-3 0-5 1-7 3-1 2-2 4-2 6l0 46c0 3 1 5 2 7 2 1 4 2 7 2l128 0c3 0 5-1 7-2 1-2 2-4 2-7z m-36-256l0-46c0-2-1-4-3-6-2-2-4-3-7-3l-54 0c-3 0-5 1-7 3-2 2-3 4-3 6l0 46c0 3 1 5 3 7 2 1 4 2 7 2l54 0c3 0 5-1 7-2 2-2 3-4 3-7z m182 119c0 40-9 77-29 110-20 34-46 60-80 80-33 20-70 29-110 29-40 0-77-9-110-29-34-20-60-46-80-80-20-33-29-70-29-110 0-40 9-77 29-110 20-34 46-60 80-80 33-20 70-29 110-29 40 0 77 9 110 29 34 20 60 46 80 80 20 33 29 70 29 110z\" transform=\"scale(0.046875 0.046875)\"><\/path><\/svg><\/div><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_3_email\" class=\"ff-el-form-control\" placeholder=\"Please fill in the email address where we can contact you\" data-name=\"email\"  aria-invalid=\"false\" aria-required=true><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label asterisk-right\"><label for='ff_3_description' id='label_ff_3_description' aria-label=\"Message\">Message<\/label><\/div><div class='ff-el-input--content'><textarea aria-required=\"false\" aria-labelledby=\"label_ff_3_description\" name=\"description\" id=\"ff_3_description\" class=\"ff-el-form-control\" placeholder=\"Request Details\" rows=\"3\" cols=\"2\" data-name=\"description\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-center ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md ff_btn_style wpf_has_custom_css\"  aria-label=\"Submit\">Submit<\/button><\/div><\/fieldset><\/form><div id='fluentform_3_errors' class='ff-errors-in-stack ff_form_instance_3_1 ff-form-loading_errors ff_form_instance_3_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_3_1 = {\"id\":\"3\",\"ajaxUrl\":\"https:\\\/\\\/cartervalves.com\\\/wp-admin\\\/admin-ajax.php\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"asteriskPlacement\":\"asterisk-right\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"cssClassName\":\"\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_3_1\",\"form_id_selector\":\"fluentform_3\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names_2[first_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names_2[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names_2[last_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names_1[first_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names_1[middle_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"names_1[last_name]\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true},\"email\":{\"value\":false,\"message\":\"Dit veld moet een geldig e-mailadres bevatten\",\"global_message\":\"This field must contain a valid email\",\"global\":true}},\"description\":{\"required\":{\"value\":false,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":true}}},\"debounce_time\":300};\n                            <\/script>\n                        <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CARTER VALVE PRODUCTS Industrial Valve Products for Critical Service Applications Carter Valve provides industrial valves and engineered packages for flow control, isolation, and overpressure protection across demanding process and utility systems. Our product portfolio covers control valves, high-performance isolation valves, safety relief solutions, steam\/condensate equipment, and engineered stations\u2014selected to help operators achieve predictable performance, lower [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-424","page","type-page","status-publish","hentry"],"acf":[],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/pages\/424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/comments?post=424"}],"version-history":[{"count":31,"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/pages\/424\/revisions"}],"predecessor-version":[{"id":854,"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/pages\/424\/revisions\/854"}],"wp:attachment":[{"href":"https:\/\/cartervalves.com\/nl\/wp-json\/wp\/v2\/media?parent=424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}