{"id":25,"count":2,"description":"Elektrische Stellantriebe erm\u00f6glichen eine pr\u00e4zise Positionierung und eine unkomplizierte Steuerungsintegration, wenn die Instrumentenluft begrenzt ist oder eine zentrale Steuerung bevorzugt wird. Wir bieten elektrische Stellantriebsoptionen, die f\u00fcr genaue Wiederholbarkeit, konfigurierbare Steuerschnittstellen und stabilen Betrieb \u00fcber definierte Arbeitszyklen ausgelegt sind. Die Merkmale konzentrieren sich auf Steuerbarkeit, Schutzart und Kompatibilit\u00e4t mit Ventilmontagestandards. Dies hilft Ihnen, die Automatisierungsarchitektur zu vereinfachen, die Positioniergenauigkeit im Regelbetrieb zu verbessern und die Abh\u00e4ngigkeit von Druckluftanlagen zu verringern.","link":"https:\/\/cartervalves.com\/de\/product-categories\/electric-actuators\/","name":"Elektrische Stellantriebe","slug":"electric-actuators","taxonomy":"product-categories","parent":13,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product-categories\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product-categories"}],"about":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/taxonomies\/product-categories"}],"up":[{"embeddable":true,"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product-categories\/13"}],"wp:post_type":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product?product-categories=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}