{"id":19,"count":2,"description":"Pneumatische Auf\/Zu- und Spezialventile sind f\u00fcr schnelles, entschlossenes Abschalten und f\u00fcr den Einsatz in der Automatisierung konzipiert. Wir bieten pneumatisch bet\u00e4tigte Ventilpakete und anwendungsspezifische Konfigurationen, bei denen Zyklusgeschwindigkeit, Wiederholbarkeit und sichere Abschaltlogik Priorit\u00e4t haben. Zu den \u00fcblichen Merkmalen geh\u00f6ren eine hohe Zyklusf\u00e4higkeit, klare Schnittstellenstandards f\u00fcr Antrieb\/Ventil und Optionen f\u00fcr anspruchsvolle Medien oder spezielle Prozessanforderungen. Dies hilft Ihnen, Ausfallzeiten aufgrund von Verkleben oder langsamem Ansprechen zu reduzieren und macht die Inbetriebnahme und Wartung vorhersehbarer.","link":"https:\/\/cartervalves.com\/de\/product-categories\/pneumatic-on-off-specialty-valves\/","name":"Pneumatische Auf\/Zu- und Spezialventile","slug":"pneumatic-on-off-specialty-valves","taxonomy":"product-categories","parent":11,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product-categories\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product-categories"}],"about":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/taxonomies\/product-categories"}],"up":[{"embeddable":true,"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product-categories\/11"}],"wp:post_type":[{"href":"https:\/\/cartervalves.com\/de\/wp-json\/wp\/v2\/product?product-categories=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}